{"id":13100,"date":"2024-03-06T16:57:26","date_gmt":"2024-03-06T09:57:26","guid":{"rendered":"https:\/\/med.siam.edu\/home2020\/?p=13100"},"modified":"2024-03-06T16:57:26","modified_gmt":"2024-03-06T09:57:26","slug":"670306","status":"publish","type":"post","link":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/","title":{"rendered":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566"},"content":{"rendered":"<div><span style=\"font-family: 'times new roman', times, serif; font-size: 14pt;\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u00a0\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36<wbr \/>\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34<wbr \/>\u0e19\u0e34\u0e01 \u0e13 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35<\/span><\/div>\n<div><span style=\"font-family: 'times new roman', times, serif; font-size: 14pt;\">\u00a0<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 14pt;\">\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e1c\u0e28.\u0e14\u0e23.\u0e1e\u0e25.\u0e23.\u0e15.\u0e2b\u0e0d\u0e34\u0e07 \u0e2a\u0e38\u0e20\u0e31\u0e17\u0e23\u0e32 \u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e27\u0e07\u0e28\u0e4c \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e41\u0e25\u0e30 \u0e28.\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13 \u0e19\u0e1e.\u0e2d\u0e21\u0e23 \u0e25\u0e35\u0e25\u0e32\u0e23\u0e31\u0e28\u0e21\u0e35 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e01\u0e25\u0e48<wbr \/>\u0e32\u0e27\u0e2d\u0e27\u0e22\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e19\u0e31<wbr \/>\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e13\u0e30\u0e2f \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e31\u0e49<wbr \/>\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e41\u0e25\u0e30 2 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e0a\u0e31\u0e49\u0e19 5 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 12 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u00a0\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e13 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35<\/p>\n","protected":false},"author":243,"featured_media":13098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[163,162,89,164,90],"tags":[],"class_list":["post-13100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faculty-event","category-news-activities","category-89","category-student-event","category-90"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u00a0\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e13 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T09:57:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670306.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kittamate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kittamate\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/\"},\"author\":{\"name\":\"kittamate\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\"},\"headline\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566\",\"datePublished\":\"2024-03-06T09:57:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670306.jpeg\",\"articleSection\":[\"faculty-event\",\"NEWS &amp; ACTIVITIES\",\"News_of_Students\",\"student-event\",\"\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/\",\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670306.jpeg\",\"datePublished\":\"2024-03-06T09:57:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/#primaryimage\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670306.jpeg\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670306.jpeg\",\"width\":864,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670306\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"description\":\"Faculty of Medicine, Siam University\",\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"width\":100,\"height\":99,\"caption\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\",\"name\":\"kittamate\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"caption\":\"kittamate\"},\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/author\\\/kittamate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/","og_locale":"en_US","og_type":"article","og_title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u00a0\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e13 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35","og_url":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/","og_site_name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","article_published_time":"2024-03-06T09:57:26+00:00","og_image":[{"width":864,"height":620,"url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670306.jpeg","type":"image\/jpeg"}],"author":"kittamate","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kittamate","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/#article","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/"},"author":{"name":"kittamate","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541"},"headline":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566","datePublished":"2024-03-06T09:57:26+00:00","mainEntityOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/"},"wordCount":0,"publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670306.jpeg","articleSection":["faculty-event","NEWS &amp; ACTIVITIES","News_of_Students","student-event","\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/","url":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/","name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/#primaryimage"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670306.jpeg","datePublished":"2024-03-06T09:57:26+00:00","breadcrumb":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/#primaryimage","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670306.jpeg","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670306.jpeg","width":864,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670306\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.siam.edu\/home2020\/"},{"@type":"ListItem","position":2,"name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19 \u0e2a\u0e39\u0e48\u0e1d\u0e31\u0e48\u0e07\u0e19\u0e19\u0e17\u0e4c\u201d \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566"}]},{"@type":"WebSite","@id":"https:\/\/med.siam.edu\/home2020\/#website","url":"https:\/\/med.siam.edu\/home2020\/","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","description":"Faculty of Medicine, Siam University","publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.siam.edu\/home2020\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/med.siam.edu\/home2020\/#organization","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","url":"https:\/\/med.siam.edu\/home2020\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","width":100,"height":99,"caption":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541","name":"kittamate","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","caption":"kittamate"},"url":"https:\/\/med.siam.edu\/home2020\/author\/kittamate\/"}]}},"_links":{"self":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/13100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/comments?post=13100"}],"version-history":[{"count":1,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/13100\/revisions"}],"predecessor-version":[{"id":13102,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/13100\/revisions\/13102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media\/13098"}],"wp:attachment":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media?parent=13100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/categories?post=13100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/tags?post=13100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}