{"id":13117,"date":"2024-03-28T14:54:03","date_gmt":"2024-03-28T07:54:03","guid":{"rendered":"https:\/\/med.siam.edu\/home2020\/?p=13117"},"modified":"2024-03-28T15:01:38","modified_gmt":"2024-03-28T08:01:38","slug":"670328-2","status":"publish","type":"post","link":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/","title":{"rendered":"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566"},"content":{"rendered":"<p><span style=\"font-family: times new roman, times, serif; font-size: 14pt;\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u00a0\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34<wbr \/>\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 6 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49<wbr \/>\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e40\u0e02\u0e15\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48 4 \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e28.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e1e.\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e0d.\u0e13\u0e34\u0e0a\u0e32\u0e20\u0e32 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48<wbr \/>\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e1e\u0e0d.\u0e2a\u0e34\u0e23\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e25\u0e34\u0e21\u0e01\u0e38\u0e25 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e31\u0e49<wbr \/>\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2f \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e01\u0e48\u0e1a\u0e31\u0e13\u0e11\u0e34<wbr \/>\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e08\u0e29\u0e0e\u0e32\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e08\u0e29\u0e0e\u0e32\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567  \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 6 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e40\u0e02\u0e15\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48 4 \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e28.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e1e.\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e0d.\u0e13\u0e34\u0e0a\u0e32\u0e20\u0e32 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e1e\u0e0d.\u0e2a\u0e34\u0e23\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e25\u0e34\u0e21\u0e01\u0e38\u0e25<\/p>\n","protected":false},"author":243,"featured_media":13119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[163,162,89,164,90],"tags":[],"class_list":["post-13117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faculty-event","category-news-activities","category-89","category-student-event","category-90"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 6 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e40\u0e02\u0e15\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48 4 \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e28.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e1e.\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e0d.\u0e13\u0e34\u0e0a\u0e32\u0e20\u0e32 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e1e\u0e0d.\u0e2a\u0e34\u0e23\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e25\u0e34\u0e21\u0e01\u0e38\u0e25\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-28T07:54:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T08:01:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670328.2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kittamate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kittamate\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/\"},\"author\":{\"name\":\"kittamate\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\"},\"headline\":\"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566\",\"datePublished\":\"2024-03-28T07:54:03+00:00\",\"dateModified\":\"2024-03-28T08:01:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670328.2-scaled.jpg\",\"articleSection\":[\"faculty-event\",\"NEWS &amp; ACTIVITIES\",\"News_of_Students\",\"student-event\",\"\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/\",\"name\":\"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670328.2-scaled.jpg\",\"datePublished\":\"2024-03-28T07:54:03+00:00\",\"dateModified\":\"2024-03-28T08:01:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670328.2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/670328.2-scaled.jpg\",\"width\":2560,\"height\":1705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/faculty-event\\\/670328-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"description\":\"Faculty of Medicine, Siam University\",\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"width\":100,\"height\":99,\"caption\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\",\"name\":\"kittamate\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"caption\":\"kittamate\"},\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/author\\\/kittamate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 6 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e40\u0e02\u0e15\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48 4 \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e28.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e1e.\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e0d.\u0e13\u0e34\u0e0a\u0e32\u0e20\u0e32 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e1e\u0e0d.\u0e2a\u0e34\u0e23\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e25\u0e34\u0e21\u0e01\u0e38\u0e25","og_url":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/","og_site_name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","article_published_time":"2024-03-28T07:54:03+00:00","article_modified_time":"2024-03-28T08:01:38+00:00","og_image":[{"width":2560,"height":1705,"url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670328.2-scaled.jpg","type":"image\/jpeg"}],"author":"kittamate","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kittamate","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/#article","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/"},"author":{"name":"kittamate","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541"},"headline":"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566","datePublished":"2024-03-28T07:54:03+00:00","dateModified":"2024-03-28T08:01:38+00:00","mainEntityOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/"},"wordCount":0,"publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670328.2-scaled.jpg","articleSection":["faculty-event","NEWS &amp; ACTIVITIES","News_of_Students","student-event","\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/","url":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/","name":"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/#primaryimage"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670328.2-scaled.jpg","datePublished":"2024-03-28T07:54:03+00:00","dateModified":"2024-03-28T08:01:38+00:00","breadcrumb":{"@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/#primaryimage","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670328.2-scaled.jpg","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2024\/03\/670328.2-scaled.jpg","width":2560,"height":1705},{"@type":"BreadcrumbList","@id":"https:\/\/med.siam.edu\/home2020\/faculty-event\/670328-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.siam.edu\/home2020\/"},{"@type":"ListItem","position":2,"name":"\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566"}]},{"@type":"WebSite","@id":"https:\/\/med.siam.edu\/home2020\/#website","url":"https:\/\/med.siam.edu\/home2020\/","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","description":"Faculty of Medicine, Siam University","publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.siam.edu\/home2020\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/med.siam.edu\/home2020\/#organization","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","url":"https:\/\/med.siam.edu\/home2020\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","width":100,"height":99,"caption":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541","name":"kittamate","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","caption":"kittamate"},"url":"https:\/\/med.siam.edu\/home2020\/author\/kittamate\/"}]}},"_links":{"self":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/13117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/comments?post=13117"}],"version-history":[{"count":2,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/13117\/revisions"}],"predecessor-version":[{"id":13121,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/13117\/revisions\/13121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media\/13119"}],"wp:attachment":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media?parent=13117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/categories?post=13117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/tags?post=13117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}