{"id":2696,"date":"2017-09-28T09:28:41","date_gmt":"2017-09-28T02:28:41","guid":{"rendered":"https:\/\/med.siam.edu\/home2020\/?p=2696"},"modified":"2017-09-28T09:42:18","modified_gmt":"2017-09-28T02:42:18","slug":"%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560","status":"publish","type":"post","link":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/","title":{"rendered":"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/med.siam.edu\/home2020\/?gallery=600916_freshy_2560\"><em>&#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 &#8211;<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 &#8211;<\/p>\n","protected":false},"author":243,"featured_media":2676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,88],"tags":[],"class_list":["post-2696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-89","category-88"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\/\u0e07\u0e32\u0e19-freshy-\u0e1b\u0e35-2560\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"og:description\" content=\"&#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 &#8211;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\/\u0e07\u0e32\u0e19-freshy-\u0e1b\u0e35-2560\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T02:28:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-28T02:42:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2017\/09\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kittamate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kittamate\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/\"},\"author\":{\"name\":\"kittamate\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\"},\"headline\":\"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560\",\"datePublished\":\"2017-09-28T02:28:41+00:00\",\"dateModified\":\"2017-09-28T02:42:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/\"},\"wordCount\":2,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg\",\"articleSection\":[\"News_of_Students\",\"\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/\",\"name\":\"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg\",\"datePublished\":\"2017-09-28T02:28:41+00:00\",\"dateModified\":\"2017-09-28T02:42:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/#primaryimage\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\\\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"description\":\"Faculty of Medicine, Siam University\",\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"width\":100,\"height\":99,\"caption\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\",\"name\":\"kittamate\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"caption\":\"kittamate\"},\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/author\\\/kittamate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\/\u0e07\u0e32\u0e19-freshy-\u0e1b\u0e35-2560\/","og_locale":"en_US","og_type":"article","og_title":"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","og_description":"&#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 &#8211;","og_url":"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\/\u0e07\u0e32\u0e19-freshy-\u0e1b\u0e35-2560\/","og_site_name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","article_published_time":"2017-09-28T02:28:41+00:00","article_modified_time":"2017-09-28T02:42:18+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2017\/09\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg","type":"image\/jpeg"}],"author":"kittamate","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kittamate"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/#article","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/"},"author":{"name":"kittamate","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541"},"headline":"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560","datePublished":"2017-09-28T02:28:41+00:00","dateModified":"2017-09-28T02:42:18+00:00","mainEntityOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/"},"wordCount":2,"commentCount":0,"publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2017\/09\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg","articleSection":["News_of_Students","\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/","url":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/","name":"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/#primaryimage"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2017\/09\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg","datePublished":"2017-09-28T02:28:41+00:00","dateModified":"2017-09-28T02:42:18+00:00","breadcrumb":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/#primaryimage","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2017\/09\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2017\/09\/\u0e40\u0e1f\u0e2a\u0e0a\u0e3516-09-60_170926_0004.jpg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%97%e0%b8%b1%e0%b9%88%e0%b8%a7%e0%b9%84%e0%b8%9b\/%e0%b8%87%e0%b8%b2%e0%b8%99-freshy-%e0%b8%9b%e0%b8%b5-2560\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.siam.edu\/home2020\/"},{"@type":"ListItem","position":2,"name":"\u0e07\u0e32\u0e19 Freshy \u0e1b\u0e35 2560 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560"}]},{"@type":"WebSite","@id":"https:\/\/med.siam.edu\/home2020\/#website","url":"https:\/\/med.siam.edu\/home2020\/","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","description":"Faculty of Medicine, Siam University","publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.siam.edu\/home2020\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/med.siam.edu\/home2020\/#organization","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","url":"https:\/\/med.siam.edu\/home2020\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","width":100,"height":99,"caption":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541","name":"kittamate","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","caption":"kittamate"},"url":"https:\/\/med.siam.edu\/home2020\/author\/kittamate\/"}]}},"_links":{"self":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/2696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/comments?post=2696"}],"version-history":[{"count":3,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/2696\/revisions"}],"predecessor-version":[{"id":2701,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/2696\/revisions\/2701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media\/2676"}],"wp:attachment":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media?parent=2696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/categories?post=2696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/tags?post=2696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}