{"id":3974,"date":"2018-11-27T16:32:36","date_gmt":"2018-11-27T09:32:36","guid":{"rendered":"https:\/\/med.siam.edu\/home2020\/?p=3974"},"modified":"2018-11-29T08:50:58","modified_gmt":"2018-11-29T01:50:58","slug":"%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018","status":"publish","type":"post","link":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/","title":{"rendered":"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018"},"content":{"rendered":"<p><span style=\"color: #0000ff; font-size: 14pt;\"><em><strong>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a0 \u0e52\u0e57\u00a0 &#8211;\u00a0 \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51\u00a0<\/strong><\/em><\/span>\u0e13<strong>\u00a0\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21<\/strong><\/p>\n<h2 class=\"post-title\" style=\"text-align: center;\"><span style=\"color: #339966;\">\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018<\/span><\/h2>\n<p>\u0e52\u0e57 &#8211; \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e52\u0e55\u0e56\u0e51 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19<br \/>\n\u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32<\/p>\n<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><a href=\"https:\/\/med.siam.edu\/home2020\/?gallery=611127_%E0%B8%AA%E0%B8%A2%E0%B8%B2%E0%B8%A1%E0%B8%99%E0%B8%B4%E0%B8%97%E0%B8%B1%E0%B8%A8%E0%B8%99%E0%B9%8C\" target=\"_blank\"><span style=\"color: #0000ff;\">&#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e23\u0e27\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19 &#8211;<\/span><\/a><\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/drive.google.com\/drive\/folders\/1c0PqAWAalZD1YZoSaAZUNFEkA_2MRKCX?usp=sharing\">\u0e20\u0e32\u0e1e\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a0 \u0e52\u0e57\u00a0 &#8211;\u00a0 \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51\u00a0\u0e13\u00a0\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 \u0e52\u0e57 &#8211; \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e52\u0e55\u0e56\u0e51 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22 &#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e23\u0e27\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19 &#8211; \u0e20\u0e32\u0e1e\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/p>\n","protected":false},"author":243,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,90],"tags":[],"class_list":["post-3974","post","type-post","status-publish","format-standard","hentry","category-89","category-90"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a0 \u0e52\u0e57\u00a0 &#8211;\u00a0 \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51\u00a0\u0e13\u00a0\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 \u0e52\u0e57 &#8211; \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e52\u0e55\u0e56\u0e51 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22 &#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e23\u0e27\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19 &#8211; \u0e20\u0e32\u0e1e\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-27T09:32:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-29T01:50:58+00:00\" \/>\n<meta name=\"author\" content=\"kittamate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kittamate\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/\"},\"author\":{\"name\":\"kittamate\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\"},\"headline\":\"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018\",\"datePublished\":\"2018-11-27T09:32:36+00:00\",\"dateModified\":\"2018-11-29T01:50:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"articleSection\":[\"News_of_Students\",\"\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/\",\"name\":\"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\"},\"datePublished\":\"2018-11-27T09:32:36+00:00\",\"dateModified\":\"2018-11-29T01:50:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"description\":\"Faculty of Medicine, Siam University\",\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"width\":100,\"height\":99,\"caption\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\",\"name\":\"kittamate\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"caption\":\"kittamate\"},\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/author\\\/kittamate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c-2018\/","og_locale":"en_US","og_type":"article","og_title":"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a0 \u0e52\u0e57\u00a0 &#8211;\u00a0 \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51\u00a0\u0e13\u00a0\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 \u0e52\u0e57 &#8211; \u0e52\u0e59 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e51 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e52\u0e55\u0e56\u0e51 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22 &#8211; \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e23\u0e27\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19 &#8211; \u0e20\u0e32\u0e1e\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14","og_url":"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c-2018\/","og_site_name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","article_published_time":"2018-11-27T09:32:36+00:00","article_modified_time":"2018-11-29T01:50:58+00:00","author":"kittamate","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kittamate"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/#article","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/"},"author":{"name":"kittamate","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541"},"headline":"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018","datePublished":"2018-11-27T09:32:36+00:00","dateModified":"2018-11-29T01:50:58+00:00","mainEntityOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"articleSection":["News_of_Students","\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/","url":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/","name":"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018 - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/#website"},"datePublished":"2018-11-27T09:32:36+00:00","dateModified":"2018-11-29T01:50:58+00:00","breadcrumb":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a2%e0%b8%b2%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a8%e0%b8%99%e0%b9%8c-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.siam.edu\/home2020\/"},{"@type":"ListItem","position":2,"name":"\u0e07\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c 2018"}]},{"@type":"WebSite","@id":"https:\/\/med.siam.edu\/home2020\/#website","url":"https:\/\/med.siam.edu\/home2020\/","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","description":"Faculty of Medicine, Siam University","publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.siam.edu\/home2020\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/med.siam.edu\/home2020\/#organization","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","url":"https:\/\/med.siam.edu\/home2020\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","width":100,"height":99,"caption":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541","name":"kittamate","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","caption":"kittamate"},"url":"https:\/\/med.siam.edu\/home2020\/author\/kittamate\/"}]}},"_links":{"self":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/3974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/comments?post=3974"}],"version-history":[{"count":3,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/3974\/revisions"}],"predecessor-version":[{"id":3977,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/3974\/revisions\/3977"}],"wp:attachment":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media?parent=3974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/categories?post=3974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/tags?post=3974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}