{"id":8564,"date":"2020-03-27T08:41:16","date_gmt":"2020-03-27T01:41:16","guid":{"rendered":"https:\/\/med.siam.edu\/home2020\/?p=8564"},"modified":"2020-03-27T08:41:16","modified_gmt":"2020-03-27T01:41:16","slug":"630327","status":"publish","type":"post","link":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/","title":{"rendered":"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet"},"content":{"rendered":"<p style=\"text-align: left;\"><span lang=\"TH\"><span class=\"_5yl5\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2563 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/span> <\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/drive.google.com\/drive\/folders\/1CV3G1ssceTF64PPYtbuDzt_3RB1XRBwI?usp=sharing\"><span style=\"color: #0000ff;\">\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e1e<\/span><\/a><\/p>\n<div dir=\"ltr\">\n<p style=\"text-align: center;\"><span lang=\"TH\">\u00a0<\/span><\/p>\n<\/div>\n<div class=\"single-post-content-text content-pad\">\n<p style=\"text-align: center;\">\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2563 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c &nbsp; \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e1e \u00a0<\/p>\n","protected":false},"author":243,"featured_media":8563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162,89,90],"tags":[],"class_list":["post-8564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-activities","category-89","category-90"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/630327\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2563 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c &nbsp; \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e1e \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/630327\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-27T01:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2020\/03\/630327.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kittamate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kittamate\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/\"},\"author\":{\"name\":\"kittamate\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\"},\"headline\":\"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet\",\"datePublished\":\"2020-03-27T01:41:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/\"},\"wordCount\":7,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/630327.jpg\",\"articleSection\":[\"NEWS &amp; ACTIVITIES\",\"News_of_Students\",\"\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/\",\"name\":\"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/630327.jpg\",\"datePublished\":\"2020-03-27T01:41:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/#primaryimage\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/630327.jpg\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/630327.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\\\/630327\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#website\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"description\":\"Faculty of Medicine, Siam University\",\"publisher\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"contentUrl\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/med-siam100.png\",\"width\":100,\"height\":99,\"caption\":\"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21\"},\"image\":{\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/#\\\/schema\\\/person\\\/b16de3978c5171339274e638e7d87541\",\"name\":\"kittamate\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g\",\"caption\":\"kittamate\"},\"url\":\"https:\\\/\\\/med.siam.edu\\\/home2020\\\/author\\\/kittamate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/630327\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2563 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e25\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c &nbsp; \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e1e \u00a0","og_url":"https:\/\/med.siam.edu\/home2020\/\u0e02\u0e48\u0e32\u0e27\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\/630327\/","og_site_name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","article_published_time":"2020-03-27T01:41:16+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2020\/03\/630327.jpg","type":"image\/jpeg"}],"author":"kittamate","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kittamate"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/#article","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/"},"author":{"name":"kittamate","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541"},"headline":"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet","datePublished":"2020-03-27T01:41:16+00:00","mainEntityOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/"},"wordCount":7,"commentCount":0,"publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2020\/03\/630327.jpg","articleSection":["NEWS &amp; ACTIVITIES","News_of_Students","\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/","url":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/","name":"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet - \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","isPartOf":{"@id":"https:\/\/med.siam.edu\/home2020\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/#primaryimage"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/#primaryimage"},"thumbnailUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2020\/03\/630327.jpg","datePublished":"2020-03-27T01:41:16+00:00","breadcrumb":{"@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/#primaryimage","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2020\/03\/630327.jpg","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2020\/03\/630327.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/med.siam.edu\/home2020\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/630327\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.siam.edu\/home2020\/"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e35\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Google Hangouts Meet"}]},{"@type":"WebSite","@id":"https:\/\/med.siam.edu\/home2020\/#website","url":"https:\/\/med.siam.edu\/home2020\/","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","description":"Faculty of Medicine, Siam University","publisher":{"@id":"https:\/\/med.siam.edu\/home2020\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.siam.edu\/home2020\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/med.siam.edu\/home2020\/#organization","name":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21","url":"https:\/\/med.siam.edu\/home2020\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/","url":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","contentUrl":"https:\/\/med.siam.edu\/home2020\/wp-content\/uploads\/2021\/03\/med-siam100.png","width":100,"height":99,"caption":"\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e22\u0e32\u0e21"},"image":{"@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/med.siam.edu\/home2020\/#\/schema\/person\/b16de3978c5171339274e638e7d87541","name":"kittamate","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8a5f9ee1bfa3169c47804eced71737b35284d2d01bae2ef96c5eaf22d565df8?s=96&d=mm&r=g","caption":"kittamate"},"url":"https:\/\/med.siam.edu\/home2020\/author\/kittamate\/"}]}},"_links":{"self":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/8564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/comments?post=8564"}],"version-history":[{"count":1,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/8564\/revisions"}],"predecessor-version":[{"id":8565,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/posts\/8564\/revisions\/8565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media\/8563"}],"wp:attachment":[{"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/media?parent=8564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/categories?post=8564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.siam.edu\/home2020\/wp-json\/wp\/v2\/tags?post=8564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}